{"id":65843,"date":"2025-09-22T10:46:09","date_gmt":"2025-09-22T08:46:09","guid":{"rendered":"https:\/\/www.eiffageenergiasistemas.com\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/"},"modified":"2025-09-23T12:25:44","modified_gmt":"2025-09-23T10:25:44","slug":"eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards","status":"publish","type":"post","link":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/","title":{"rendered":"Eiffage Energ\u00eda Sistemas continues to work to maintain and improve its occupational safety standards"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.eiffageenergiasistemas.com\/en\/\">Eiffage Energ\u00eda Sistemas<\/a> received recognition for its commitment to occupational safety in the programme &#8220;En Profundidad&#8221; (In Depth) on <a href=\"https:\/\/www.cmmedia.es\/\">Castilla-La Mancha Media<\/a>, broadcast on 20 September 2025.<\/p>\n\n<p>This report highlights the policies and actions implemented by the company to reduce workplace accidents and promote a safe working environment. <\/p>\n\n<p>People&#8217;s safety is an essential value for this company. Since 2010, it has managed to reduce the frequency rate with sick leave &#8211; the number of accidents per million hours worked &#8211; from 59.76 to 1.92 in December 2024, reflecting its sustained commitment to prevention and continuous improvement of working conditions. <\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Strategies Implemented<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li><strong>Safety Week<\/strong>: every year since 2012, it has organised a week dedicated to occupational safety, with awareness-raising activities, talks and workshops, in which the chain of command leads the actions to reinforce the culture of prevention.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li><strong>Risk Assessments<\/strong>: Before starting any task, written risk assessments are carried out to identify and mitigate potential hazards.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li><strong>Safety Inspections<\/strong>: The company carries out more than 5,000 safety inspections annually to ensure compliance with regulations and identify areas for improvement.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li><strong>Certifications<\/strong>: since 2012, it has been certified to OHSAS 18001:2007 in occupational risk prevention management, which evolved into ISO 45001:2018 in 2019.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\"><strong>Feature in &#8220;En Profundidad&#8221; <\/strong><\/h3>\n\n<p>The report broadcast by Castilla-La Mancha Media takes an in-depth look at the initiatives and results achieved by Eiffage Energ\u00eda Sistemas in the field of occupational safety. The programme offers a detailed overview of the actions implemented and testimonials from professionals involved in promoting a safe working environment. <\/p>\n\n<p>Eiffage Energ\u00eda Sistemas continues to work to maintain and improve its occupational safety standards, ensuring the well-being of its employees and contributing to the creation of safer working environments in the energy sector. <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"65792\" src=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-09-683x1024.jpg\" alt=\"\" class=\"wp-image-65792\" srcset=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-09-683x1024.jpg 683w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-09-200x300.jpg 200w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-09.jpg 720w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"65784\" src=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-04-683x1024.jpg\" alt=\"\" class=\"wp-image-65784\" srcset=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-04-683x1024.jpg 683w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-04-200x300.jpg 200w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-04.jpg 720w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"65788\" src=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-10-683x1024.jpg\" alt=\"\" class=\"wp-image-65788\" srcset=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-10-683x1024.jpg 683w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-10-200x300.jpg 200w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-10.jpg 720w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"65789\" src=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-29-1024x683.jpg\" alt=\"\" class=\"wp-image-65789\" srcset=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-29-1024x683.jpg 1024w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-29-300x200.jpg 300w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-29-768x512.jpg 768w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-29.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"65782\" src=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-35-1024x683.jpg\" alt=\"\" class=\"wp-image-65782\" srcset=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-35-1024x683.jpg 1024w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-35-300x200.jpg 300w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-35-768x512.jpg 768w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-35.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-26-1024x683.jpg\" alt=\"\" class=\"wp-image-65794\" srcset=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-26-1024x683.jpg 1024w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-26-300x200.jpg 300w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-26-768x512.jpg 768w, https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-26.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Feature article:<\/h3>\n\n<p><a href=\"CMMedia: 'Luchar contra la siniestralidad laboral' - En Profundidad\" target=\"_blank\" rel=\"noreferrer noopener\">CMMedia: &#8216;Luchar contra la siniestralidad laboral&#8217; &#8211; En Profundidad<\/a> <\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eiffage Energ\u00eda Sistemas received recognition for its commitment to occupational safety in the programme &#8220;En Profundidad&#8221; (In Depth) on Castilla-La Mancha Media, broadcast on 20 September 2025. This report highlights the policies and actions implemented by the company to reduce workplace accidents and promote a safe working environment. People&#8217;s safety is an essential value for &#8230; <a title=\"Eiffage Energ\u00eda Sistemas continues to work to maintain and improve its occupational safety standards\" class=\"read-more\" href=\"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/\" aria-label=\"Read more about Eiffage Energ\u00eda Sistemas continues to work to maintain and improve its occupational safety standards\">Read more<\/a><\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1941,1893],"tags":[1949,1662,1713,1716,2205],"class_list":["post-65843","post","type-post","status-publish","format-standard","hentry","category-eiffage-energia-sistemas-en","category-job-security","tag-eiffage-energia-sistemas-en","tag-health-and-safety","tag-occupational-health","tag-occupational-risk-prevention","tag-safety-work"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eiffage Energ\u00eda Sistemas in CMMedia&#039;s \u2018In Depth\u2019<\/title>\n<meta name=\"description\" content=\"Eiffage Energ\u00eda Sistemas en el programa &quot;En Profundidad&quot;, de CMMedia, donde ha sido reconocida por su compromiso con la seguridad laboral.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eiffage Energ\u00eda Sistemas in CMMedia&#039;s \u2018In Depth\u2019\" \/>\n<meta property=\"og:description\" content=\"Eiffage Energ\u00eda Sistemas en el programa &quot;En Profundidad&quot;, de CMMedia, donde ha sido reconocida por su compromiso con la seguridad laboral.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/\" \/>\n<meta property=\"og:site_name\" content=\"Eiffage Energ\u00eda Sistemas\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-22T08:46:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-23T10:25:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-09.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristina Martinez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/2025\\\/09\\\/22\\\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/2025\\\/09\\\/22\\\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\\\/\"},\"author\":{\"name\":\"Cristina Martinez\",\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/#\\\/schema\\\/person\\\/d4a1df7018b98e1c5037080a554ff67b\"},\"headline\":\"Eiffage Energ\u00eda Sistemas continues to work to maintain and improve its occupational safety standards\",\"datePublished\":\"2025-09-22T08:46:09+00:00\",\"dateModified\":\"2025-09-23T10:25:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/2025\\\/09\\\/22\\\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\\\/\"},\"wordCount\":302,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/2025\\\/09\\\/22\\\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/prevencion-cmm-tv-09-683x1024.jpg\",\"keywords\":[\"Eiffage Energ\u00eda Sistemas\",\"Health and Safety\",\"OCCUPATIONAL HEALTH\",\"Occupational risk prevention\",\"Safety work\"],\"articleSection\":[\"Eiffage Energ\u00eda Sistemas\",\"job security\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/2025\\\/09\\\/22\\\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\\\/\",\"url\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/2025\\\/09\\\/22\\\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\\\/\",\"name\":\"Eiffage Energ\u00eda Sistemas in CMMedia's \u2018In Depth\u2019\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/2025\\\/09\\\/22\\\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/2025\\\/09\\\/22\\\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/prevencion-cmm-tv-09-683x1024.jpg\",\"datePublished\":\"2025-09-22T08:46:09+00:00\",\"dateModified\":\"2025-09-23T10:25:44+00:00\",\"description\":\"Eiffage Energ\u00eda Sistemas en el programa \\\"En Profundidad\\\", de CMMedia, donde ha sido reconocida por su compromiso con la seguridad laboral.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/2025\\\/09\\\/22\\\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/2025\\\/09\\\/22\\\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/2025\\\/09\\\/22\\\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/prevencion-cmm-tv-09-683x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/prevencion-cmm-tv-09-683x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/2025\\\/09\\\/22\\\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eiffage Energ\u00eda Sistemas continues to work to maintain and improve its occupational safety standards\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/\",\"name\":\"Eiffage Energ\u00eda Sistemas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/#organization\",\"name\":\"Eiffage Energ\u00eda Sistemas\",\"url\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-eiffage-energia-sistemas-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-cropped-eiffage-energia-sistemas-logo-1.png\",\"width\":741,\"height\":250,\"caption\":\"Eiffage Energ\u00eda Sistemas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/#\\\/schema\\\/person\\\/d4a1df7018b98e1c5037080a554ff67b\",\"name\":\"Cristina Martinez\",\"url\":\"https:\\\/\\\/www.eiffageenergiasistemas.com\\\/en\\\/author\\\/cristinamartinez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eiffage Energ\u00eda Sistemas in CMMedia's \u2018In Depth\u2019","description":"Eiffage Energ\u00eda Sistemas en el programa \"En Profundidad\", de CMMedia, donde ha sido reconocida por su compromiso con la seguridad laboral.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/","og_locale":"en_US","og_type":"article","og_title":"Eiffage Energ\u00eda Sistemas in CMMedia's \u2018In Depth\u2019","og_description":"Eiffage Energ\u00eda Sistemas en el programa \"En Profundidad\", de CMMedia, donde ha sido reconocida por su compromiso con la seguridad laboral.","og_url":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/","og_site_name":"Eiffage Energ\u00eda Sistemas","article_published_time":"2025-09-22T08:46:09+00:00","article_modified_time":"2025-09-23T10:25:44+00:00","og_image":[{"width":720,"height":1080,"url":"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-09.jpg","type":"image\/jpeg"}],"author":"Cristina Martinez","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/#article","isPartOf":{"@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/"},"author":{"name":"Cristina Martinez","@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/#\/schema\/person\/d4a1df7018b98e1c5037080a554ff67b"},"headline":"Eiffage Energ\u00eda Sistemas continues to work to maintain and improve its occupational safety standards","datePublished":"2025-09-22T08:46:09+00:00","dateModified":"2025-09-23T10:25:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/"},"wordCount":302,"publisher":{"@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/#organization"},"image":{"@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-09-683x1024.jpg","keywords":["Eiffage Energ\u00eda Sistemas","Health and Safety","OCCUPATIONAL HEALTH","Occupational risk prevention","Safety work"],"articleSection":["Eiffage Energ\u00eda Sistemas","job security"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/","url":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/","name":"Eiffage Energ\u00eda Sistemas in CMMedia's \u2018In Depth\u2019","isPartOf":{"@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/#primaryimage"},"image":{"@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-09-683x1024.jpg","datePublished":"2025-09-22T08:46:09+00:00","dateModified":"2025-09-23T10:25:44+00:00","description":"Eiffage Energ\u00eda Sistemas en el programa \"En Profundidad\", de CMMedia, donde ha sido reconocida por su compromiso con la seguridad laboral.","breadcrumb":{"@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/#primaryimage","url":"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-09-683x1024.jpg","contentUrl":"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2025\/09\/prevencion-cmm-tv-09-683x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/2025\/09\/22\/eiffage-energia-sistemas-continues-to-work-to-maintain-and-improve-its-occupational-safety-standards\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eiffageenergiasistemas.com\/en\/"},{"@type":"ListItem","position":2,"name":"Eiffage Energ\u00eda Sistemas continues to work to maintain and improve its occupational safety standards"}]},{"@type":"WebSite","@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/#website","url":"https:\/\/www.eiffageenergiasistemas.com\/en\/","name":"Eiffage Energ\u00eda Sistemas","description":"","publisher":{"@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eiffageenergiasistemas.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/#organization","name":"Eiffage Energ\u00eda Sistemas","url":"https:\/\/www.eiffageenergiasistemas.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-eiffage-energia-sistemas-logo-1.png","contentUrl":"https:\/\/www.eiffageenergiasistemas.com\/wp-content\/uploads\/2022\/05\/cropped-cropped-eiffage-energia-sistemas-logo-1.png","width":741,"height":250,"caption":"Eiffage Energ\u00eda Sistemas"},"image":{"@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eiffageenergiasistemas.com\/en\/#\/schema\/person\/d4a1df7018b98e1c5037080a554ff67b","name":"Cristina Martinez","url":"https:\/\/www.eiffageenergiasistemas.com\/en\/author\/cristinamartinez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eiffageenergiasistemas.com\/en\/wp-json\/wp\/v2\/posts\/65843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eiffageenergiasistemas.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eiffageenergiasistemas.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eiffageenergiasistemas.com\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eiffageenergiasistemas.com\/en\/wp-json\/wp\/v2\/comments?post=65843"}],"version-history":[{"count":0,"href":"https:\/\/www.eiffageenergiasistemas.com\/en\/wp-json\/wp\/v2\/posts\/65843\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eiffageenergiasistemas.com\/en\/wp-json\/wp\/v2\/media?parent=65843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eiffageenergiasistemas.com\/en\/wp-json\/wp\/v2\/categories?post=65843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eiffageenergiasistemas.com\/en\/wp-json\/wp\/v2\/tags?post=65843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}